{"id":33895,"date":"2025-10-21T15:21:15","date_gmt":"2025-10-21T13:21:15","guid":{"rendered":"https:\/\/iview.io\/informatec-wins-harrer-partner-as-new-iview-reseller-for-the-austrian-market\/"},"modified":"2025-10-21T15:31:39","modified_gmt":"2025-10-21T13:31:39","slug":"informatec-wins-harrer-partner-as-new-iview-reseller-for-the-austrian-market","status":"publish","type":"post","link":"https:\/\/iview.io\/de\/informatec-wins-harrer-partner-as-new-iview-reseller-for-the-austrian-market\/","title":{"rendered":"Informatec gewinnt Harrer &amp; Partner als neuen iVIEW-Reseller f\u00fcr den \u00f6sterreichischen Markt"},"content":{"rendered":"\n<p><strong><em><strong><em>Informatec und Harrer &amp; Partner b\u00fcndeln ihre Expertise, um Qlik-Kunden in \u00d6sterreich leistungsstarke L\u00f6sungen f\u00fcr Data Governance, ETL-Automatisierung und BI-Migration mit iVIEW Dataflow und iVIEW Library anzubieten.<\/em><\/strong><\/em><\/strong><\/p>\n\n<p>Muttenz, 21.10.2025 &#8211; Informatec, der Schweizer Data &amp; AI Spezialist f\u00fcr datengetriebene Business-Intelligence-L\u00f6sungen, gibt die neue Partnerschaft mit Harrer &amp; Partner bekannt. Der etablierte \u00f6sterreichische Qlik-Partner wird k\u00fcnftig als Reseller f\u00fcr das iVIEW Data Automation Framework agieren und damit seinen Kunden leistungsstarke Tools f\u00fcr eine moderne, automatisierte BI-Landschaft anbieten. <\/p>\n\n<p>Die L\u00f6sungssuite iVIEW, bestehend aus den Modulen iVIEW Dataflow und iVIEW Library, vereint bew\u00e4hrte Best Practices aus zahlreichen Qlik-Projekten in einer integrierten Plattform.<br\/>iVIEW Dataflow automatisiert komplexe ETL-Prozesse und sorgt f\u00fcr Effizienz im Datenmanagement, w\u00e4hrend iVIEW Library eine zentrale Governance-Plattform f\u00fcr Berechnungen, KPIs und Gesch\u00e4ftslogik schafft. <\/p>\n\n<p>Gemeinsam unterst\u00fctzen beide Produkte Unternehmen unter anderem dabei, Migrationsprojekte von QlikView auf Qlik Sense bzw. Qlik Cloud strukturiert, transparent und mit deutlich geringerem Aufwand umzusetzen.<\/p>\n\n<p>Immer mehr Qlik-Kunden in der DACH-Region setzen bereits auf iVIEW, um ihre Daten- und Analyseprozesse zu vereinfachen, zu automatisieren und langfristig zu professionalisieren. Damit etabliert sich iVIEW zunehmend als Standardl\u00f6sung f\u00fcr Data Governance und Automatisierung im Qlik-Umfeld. <\/p>\n\n<p><em>&#8222;Wir freuen uns sehr \u00fcber die Partnerschaft mit Harrer &amp; Partner und die M\u00f6glichkeit, deren Kunden dabei zu helfen, ihre Qlik-BI-Landschaften auf die n\u00e4chste Stufe zu heben. In iVIEW stecken mehr als 25 Jahre Erfahrung und Best Practices aus unz\u00e4hligen Qlik-Projekten &#8211; diese Expertise zusammen mit einem so etablierten Partner wie H&amp;P nach \u00d6sterreich zu bringen, ist ein fantastischer Schritt f\u00fcr uns.&#8220;<\/em>  Rino Mentil, CEO &amp; Gr\u00fcnder, Informatec<\/p>\n\n<p>Harrer &amp; Partner sieht auch einen klaren strategischen Wert in der Erweiterung seines Portfolios durch diese Kooperation: <em>&#8222;iVIEW Dataflow und iVIEW Library sind f\u00fcr uns die perfekte Erg\u00e4nzung zu Qlik Sense &#8211; denn sie automatisieren Datenfl\u00fcsse, vereinfachen die Governance und helfen unseren Kunden, ihre BI-Umgebungen nachhaltig zu professionalisieren.&#8220;<\/em> Elfriede Harrer, Gesch\u00e4ftsf\u00fchrerin, <a href=\"https:\/\/www.hpartner.at\/2025\/10\/14\/harrer-partner-erweitert-qlik-sense-portfolio-mit-iview-dataflow-und-iview-library-von-informatec\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/www.hpartner.at\/2025\/10\/14\/harrer-partner-erweitert-qlik-sense-portfolio-mit-iview-dataflow-und-iview-library-von-informatec\/\" rel=\"noreferrer noopener\">Harrer &amp; Partner <\/a> <\/p>\n\n<p>Mit dieser Partnerschaft st\u00e4rkt Informatec seine Marktpr\u00e4senz in \u00d6sterreich und bietet Unternehmen eine innovative Plattform, um ihre Datenprozesse effizient, transparent und mit KI-gesteuerter Intelligenz weiterzuentwickeln.<strong><strong><br\/><\/strong><\/strong><\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informatec und Harrer &amp; Partner b\u00fcndeln ihre Expertise, um Qlik-Kunden in \u00d6sterreich leistungsstarke L\u00f6sungen f\u00fcr Data Governance, ETL-Automatisierung und BI-Migration mit iVIEW Dataflow und iVIEW Library anzubieten. Muttenz, 21.10.2025 &#8211; Informatec, der Schweizer Data &amp; AI Spezialist f\u00fcr datengetriebene Business-Intelligence-L\u00f6sungen, gibt die neue Partnerschaft mit Harrer &amp; Partner bekannt. Der etablierte \u00f6sterreichische Qlik-Partner wird k\u00fcnftig [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":33893,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[25],"tags":[57,72,41,69,68],"class_list":["post-33895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artikel","tag-iview-de","tag-partnerschaft","tag-qlik-de","tag-qlik-migration-de","tag-qlik-umzug-in-die-cloud"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 18:20:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/iview.io\/de\/wp-json\/wp\/v2\/posts\/33895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iview.io\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iview.io\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iview.io\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/iview.io\/de\/wp-json\/wp\/v2\/comments?post=33895"}],"version-history":[{"count":5,"href":"https:\/\/iview.io\/de\/wp-json\/wp\/v2\/posts\/33895\/revisions"}],"predecessor-version":[{"id":33901,"href":"https:\/\/iview.io\/de\/wp-json\/wp\/v2\/posts\/33895\/revisions\/33901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iview.io\/de\/wp-json\/wp\/v2\/media\/33893"}],"wp:attachment":[{"href":"https:\/\/iview.io\/de\/wp-json\/wp\/v2\/media?parent=33895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iview.io\/de\/wp-json\/wp\/v2\/categories?post=33895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iview.io\/de\/wp-json\/wp\/v2\/tags?post=33895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}